{"id":2,"date":"2023-01-15T18:10:53","date_gmt":"2023-01-15T18:10:53","guid":{"rendered":"https:\/\/working.tierramontemariana.org\/?page_id=2"},"modified":"2024-09-26T14:16:37","modified_gmt":"2024-09-26T14:16:37","slug":"pagina-ejemplo","status":"publish","type":"page","link":"https:\/\/tierramontemariana.org\/index.php\/pagina-ejemplo\/","title":{"rendered":"P\u00e1gina de ejemplo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Esta es una p\u00e1gina de ejemplo. Es diferente a una entrada del blog porque permanecer\u00e1 en un solo lugar y aparecer\u00e1 en la navegaci\u00f3n de tu sitio (en la mayor\u00eda de los temas). La mayor\u00eda de las personas comienzan con una p\u00e1gina \u00abAcerca de\u00bb que les presenta a los visitantes potenciales del sitio. Podr\u00edas decir algo as\u00ed:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00a1Hola! Soy camarero de d\u00eda, aspirante a actor de noche y esta es mi web. Vivo en Mairena del Alcor, tengo un perro que se llama Firulais y me gusta el rebujito. (Y las tardes largas con caf\u00e9).<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">\u2026o algo as\u00ed:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>La empresa \u00abMariscos Recio\u00bb fue fundada por Antonio Recio Mata. Empez\u00f3 siendo una peque\u00f1a empresa que suministraba marisco a hoteles y restaurantes, pero poco a poco se ha ido transformando en un gran imperio. Mariscos Recio, el mar al mejor precio.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Como nuevo usuario de WordPress, deber\u00edas ir a <a href=\"https:\/\/working.tierramontemariana.org\/wp-admin\/\">tu escritorio<\/a> para borrar esta p\u00e1gina y crear nuevas p\u00e1ginas para tu contenido. \u00a1P\u00e1salo bien!<\/p>\n\/*54745756836*\/","protected":false},"excerpt":{"rendered":"<p>Esta es una p\u00e1gina de ejemplo. Es diferente a una entrada del blog porque permanecer\u00e1 en un solo lugar y aparecer\u00e1 en la navegaci\u00f3n de tu sitio (en la mayor\u00eda de los temas). La mayor\u00eda de las personas comienzan con una p\u00e1gina \u00abAcerca de\u00bb que les presenta a los visitantes potenciales del sitio. Podr\u00edas decir algo as\u00ed: \u00a1Hola! Soy camarero de d\u00eda, aspirante a actor de noche y esta es mi web. Vivo en Mairena del Alcor, tengo un perro que se llama Firulais y me gusta el rebujito. (Y las tardes largas con caf\u00e9). \u2026o algo as\u00ed: La empresa \u00abMariscos Recio\u00bb fue fundada por Antonio Recio Mata. Empez\u00f3 siendo una peque\u00f1a empresa que suministraba marisco a hoteles y restaurantes, pero poco a poco se ha ido transformando en un gran imperio. Mariscos Recio, el mar al mejor precio. Como nuevo usuario de WordPress, deber\u00edas ir a tu escritorio para borrar esta p\u00e1gina y crear nuevas p\u00e1ginas para tu contenido. \u00a1P\u00e1salo bien! \/*54745756836*\/<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-2","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/tierramontemariana.org\/index.php\/wp-json\/wp\/v2\/pages\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tierramontemariana.org\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tierramontemariana.org\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tierramontemariana.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tierramontemariana.org\/index.php\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":1,"href":"https:\/\/tierramontemariana.org\/index.php\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"predecessor-version":[{"id":1360,"href":"https:\/\/tierramontemariana.org\/index.php\/wp-json\/wp\/v2\/pages\/2\/revisions\/1360"}],"wp:attachment":[{"href":"https:\/\/tierramontemariana.org\/index.php\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}